{"id":9150,"date":"2023-08-10T19:45:38","date_gmt":"2023-08-10T22:45:38","guid":{"rendered":"https:\/\/keltec.com.br\/produto\/ka150-044-3\/"},"modified":"2026-07-01T15:40:34","modified_gmt":"2026-07-01T18:40:34","slug":"ka150-044","status":"publish","type":"product","link":"https:\/\/keltec.com.br\/de\/produkt\/ka150-044\/","title":{"rendered":"KA150-044"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":36073,"template":"","meta":[],"product_brand":[],"product_cat":[15],"product_tag":[],"marca":[13404,14221,14589,14222,14223,14594,14224,14220,20997,14225,14226,21025,21027,21029,21031,14227,14613,14228],"class_list":["post-9150","product","type-product","status-publish","has-post-thumbnail","product_cat-filtros-do-ar-elementos","marca-ingersoll-rand","marca-ssr-ep40se-b-40-hp","marca-ssr-ep50se-50-hp-86-bar","marca-ssr-ep50se-b091310049-50-hp-86-bar-set-13","marca-ssr-ep50se-b-50-hp-86-bar","marca-ssr-ep60se-60-hp","marca-ssr-hp40se-b-40-hp-96-bar","marca-ssr-hp50se-50-hp-96-bar","marca-ssr-hp60se-60hp-jun-05","marca-ssr-hxp40se-b-40-hp-138-bar","marca-ssr-hxp50se-50-hp-138-bar","marca-ssr-mh37se-50hp-138bar-jun-05","marca-ssr-ml37se-50hp-138bar-jun-05","marca-ssr-mm37se-50hp-138bar-jun-05","marca-ssr-mu37se-50hp-138bar-80440464-jun-05","marca-ssr-xf30s-30-hp-69-bar","marca-ssr-xf50se-50-hp-69-bar","marca-ssr-xf50sf-50-hp-69-bar","first","instock","product-type-simple"],"_links":{"self":[{"href":"https:\/\/keltec.com.br\/de\/wp-json\/wp\/v2\/product\/9150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/keltec.com.br\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/keltec.com.br\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/keltec.com.br\/de\/wp-json\/wp\/v2\/media\/36073"}],"wp:attachment":[{"href":"https:\/\/keltec.com.br\/de\/wp-json\/wp\/v2\/media?parent=9150"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/keltec.com.br\/de\/wp-json\/wp\/v2\/product_brand?post=9150"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/keltec.com.br\/de\/wp-json\/wp\/v2\/product_cat?post=9150"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/keltec.com.br\/de\/wp-json\/wp\/v2\/product_tag?post=9150"},{"taxonomy":"marca","embeddable":true,"href":"https:\/\/keltec.com.br\/de\/wp-json\/wp\/v2\/marca?post=9150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}