{"id":9828,"date":"2023-08-10T19:48:16","date_gmt":"2023-08-10T22:48:16","guid":{"rendered":"https:\/\/keltec.com.br\/produto\/kx500-032-2\/"},"modified":"2026-07-08T17:23:52","modified_gmt":"2026-07-08T20:23:52","slug":"kx500-032","status":"publish","type":"product","link":"https:\/\/keltec.com.br\/de\/produkt\/kx500-032\/","title":{"rendered":"KX500-032"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":49947,"template":"","meta":[],"product_brand":[],"product_cat":[2701],"product_tag":[],"marca":[13406,21621,21620,21622,21624,21627,21623,21625,21626,15182,15181,15187,21275,21277,21273,21271,21269,15200,15198,15199,15192,15190,15191,15197,15195,15196,15194,15193,15223,15221,15222,15217,15215,15216,15220,15218,15219,15210,15213,15214,15212,15174,15175],"class_list":["post-9828","product","type-product","status-publish","has-post-thumbnail","product_cat-reparo-de-valvulas","marca-atlas-copco","marca-g160vsdw-wuxi-42-75-85-10","marca-g160w-wuxi-42-75-85-10","marca-g200-w-wuxi-42-10","marca-g200-w-wuxi-42-75-85","marca-g200vsd-w-wuxi-42-10bar","marca-g250-w-wuxi-42-10","marca-g250-w-wuxi-42-75-85","marca-g250vsd-w-wuxi-42-10bar","marca-ga110-brp071853-03-2011-150-hp-104-138bar","marca-ga110-brp071853-03-2011-150-hp-52-69-86bar","marca-ga132-apack-brp076034-fev-2011-c190-177-hp-69-86-104-bar","marca-ga132-gazelle-bqd105726-104hp","marca-ga132-gazelle-bqd105726-138hp","marca-ga132-gazelle-bqd105726-52hp","marca-ga132-gazelle-bqd105726-86hp","marca-ga132-gazelle-bqd105726-69hp","marca-ga132-bqd102693-05-2015-177-hp-104-138bar","marca-ga132-bqd102693-05-2015-177-hp-52bar","marca-ga132-bqd102693-05-2015-177-hp-69-86bar","marca-ga132-brp071853-03-2011-177-hp-104-138bar","marca-ga132-brp071853-03-2011-177-hp-52bar","marca-ga132-brp071853-03-2011-177-hp-69-86bar","marca-ga132-brp084244-01-2014-177-hp-104-138bar","marca-ga132-brp084244-01-2014-177-hp-52bar","marca-ga132-brp084244-01-2014-177-hp-69-86bar","marca-ga132vsd-brp071853-07-2012-177-hp-104-bar","marca-ga132vsd-brp071853-07-2012-177-hp-86-bar","marca-ga160-bqd102693-05-2015-200-hp-138bar","marca-ga160-bqd102693-05-2015-200-hp-69bar","marca-ga160-bqd102693-05-2015-200-hp-86-104bar","marca-ga160-brp071853-07-2012-200-hp-138bar","marca-ga160-brp071853-07-2012-200-hp-69bar","marca-ga160-brp071853-07-2012-200-hp-86-104bar","marca-ga160-brp084244-01-2014-200-hp-138bar","marca-ga160-brp084244-01-2014-200-hp-69bar","marca-ga160-brp084244-01-2014-200-hp-86-104bar","marca-ga160apack-brp076034-fev-2011-200-hp-69-86-104-bar","marca-ga160vsd-brp071853-nov-2010-200-hp-104-bar","marca-ga160vsd-brp071853-nov-2010-200-hp-138-bar","marca-ga160vsd-brp071853-nov-2010-200-hp-86-bar","marca-ga90-brp071853-03-2011-125-hp-52-69bar","marca-ga90-brp071853-03-2011-125-hp-86-104-138bar","first","instock","product-type-simple"],"_links":{"self":[{"href":"https:\/\/keltec.com.br\/de\/wp-json\/wp\/v2\/product\/9828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/keltec.com.br\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/keltec.com.br\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/keltec.com.br\/de\/wp-json\/wp\/v2\/media\/49947"}],"wp:attachment":[{"href":"https:\/\/keltec.com.br\/de\/wp-json\/wp\/v2\/media?parent=9828"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/keltec.com.br\/de\/wp-json\/wp\/v2\/product_brand?post=9828"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/keltec.com.br\/de\/wp-json\/wp\/v2\/product_cat?post=9828"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/keltec.com.br\/de\/wp-json\/wp\/v2\/product_tag?post=9828"},{"taxonomy":"marca","embeddable":true,"href":"https:\/\/keltec.com.br\/de\/wp-json\/wp\/v2\/marca?post=9828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}