{"id":9456,"date":"2023-08-10T19:46:51","date_gmt":"2023-08-10T22:46:51","guid":{"rendered":"https:\/\/keltec.com.br\/produto\/kl1000-064-2\/"},"modified":"2026-04-07T10:20:32","modified_gmt":"2026-04-07T13:20:32","slug":"kl1000-064","status":"publish","type":"product","link":"https:\/\/keltec.com.br\/it\/prodotto\/kl1000-064\/","title":{"rendered":"KL1000-064"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":43332,"template":"","meta":[],"product_brand":[],"product_cat":[2698],"product_tag":[],"marca":[16246,16248,16275,16319,16276,16320,16277,16321,16278,16322,16111,16340,16324,16112,16327,16328,16113,16330,16332,16333,16114,16334,16335,16357,16337,16338,16339,16358,16359,16360,16361,16371,16372,16373,16374,16424,16425,16426,16427,16428,16430,16431,16432,16433,16434,16435,16436,16438,16437,16439,16440,16377,16378,16379,16380,16362,16140,16363,16141,16228,16229,16381,16230,16382,16383,16384,16385,16386,16387,16441,16442,16388,16389,13420,13989,16364,13990,16365,16349,16350,16443,16444,16445,16446,16447,16448,16449,16450,13423,19172,19173,19174,19176,21068,16121,16252,16123,16122,16124,16125,16126,16366,16451,16452,16231,16115,16117,16118,16250,16120,16119,14765,16028],"class_list":{"0":"post-9456","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-filtros-do-oleo-elementos","7":"marca-csd-100-75-kw-8-11-15-bar-08-2011","8":"marca-csd-125-90-kw-8-11-15-bar-08-2011","9":"marca-ds-140","10":"marca-ds-141","11":"marca-ds-170","12":"marca-ds-171","13":"marca-ds-200","14":"marca-ds-201","15":"marca-ds-220","16":"marca-ds-241","17":"marca-dsd-100","18":"marca-dsd-100-75-kw-9-bar","19":"marca-dsd-100s-75-kw-8-11-15-bar","20":"marca-dsd-125-07-2007","21":"marca-dsd-125-air-cooled-with-sigma-control-90-kw-12-bar","22":"marca-dsd-142","23":"marca-dsd-150-07-2007","24":"marca-dsd-150-air-cooled-with-sigma-control-110-kw-8-11-15-bar-2006","25":"marca-dsd-172-90-kw-8-12-bar","26":"marca-dsd-172t-90-kw-8-12-bar","27":"marca-dsd-175-132-kw-07-2007","28":"marca-dsd-175-132-kw-8-12-15-bar","29":"marca-dsd-175t-132-kw-8-12-15-bar","30":"marca-dsd-200-160-kw-07-2007","31":"marca-dsd-200-air-cooled-with-sigma-control-160-kw-8-11-15-bar","32":"marca-dsd-202-8-11-15-bar","33":"marca-dsd-238-8-11-15-bar","34":"marca-dsd-250-8-11-15-bar-07-2007","35":"marca-dsdx-200-132-kw-8-11-15-bar","36":"marca-dsdx-243","37":"marca-dsdx-250-160-kw-8-12-15-bar","38":"marca-es-240","39":"marca-es-250","40":"marca-es-280","41":"marca-es-300","42":"marca-esd-150-air-cooled-with-sigma-control-110-kw-8-11-15-bar-2006","43":"marca-esd-200","44":"marca-esd-250-200-kw-8-12-15-bar","45":"marca-esd-250-versao-2-200-kw-8-12-15-bar","46":"marca-esd-250-versao-3-200-kw-8-12-15-bar","47":"marca-esd-251","48":"marca-esd-251-2006","49":"marca-esd-300-250-kw-8-10-15-bar","50":"marca-esd-301","51":"marca-esd-301-2006","52":"marca-esd-351","53":"marca-esd-351-2006","54":"marca-esd-361-2006","55":"marca-esd-361-200-kw-8-bar","56":"marca-esd-441","57":"marca-esd-441-2006","58":"marca-esg-240","59":"marca-esg-250","60":"marca-esg-280","61":"marca-esg-300","62":"marca-fs-360","63":"marca-fs-360-antigo","64":"marca-fs-440","65":"marca-fs-440-antigo","66":"marca-fsd-315","67":"marca-fsd-350","68":"marca-fsd-360-250-kw-8-10-12-bar","69":"marca-fsd-400","70":"marca-fsd-440-315-kw-8-12-13-bar","71":"marca-fsg-300-160-kw-6-8-10-bar","72":"marca-fsg-350-200-kw-6-8-10-bar","73":"marca-fsg-360","74":"marca-fsg-420-250-kw-6-8-10-bar","75":"marca-fsg-440","76":"marca-fsg-500-315-kw-6-8-10-bar","77":"marca-fsg-501-315-kw-10-bar","78":"marca-fsg-560","79":"marca-fsg-620","80":"marca-gardner-denver","81":"marca-gs-590-from-serial-n591001-up-to-592000","82":"marca-gs-590-from-serial-n592001","83":"marca-gs-650-from-serial-n651001-up-to-652000","84":"marca-gs-650-from-serial-n652001","85":"marca-hs-690","86":"marca-hs-760","87":"marca-hsd-500-360-kw-8-12-15-bar","88":"marca-hsd-550-400-kw-8-12-15-bar","89":"marca-hsd-600-450-kw-8-12-15-bar","90":"marca-hsd-650-500-kw-8-12-15-bar","91":"marca-hsd-651","92":"marca-hsd-711","93":"marca-hsd-761","94":"marca-hsd-831","95":"marca-kaeser","96":"marca-m123-1","97":"marca-m200-cat-c6-6acert-01-2011","98":"marca-m220-14-18","99":"marca-m250-om936la","100":"marca-m255-cummins-b6-7","101":"marca-sfc-110-110-kw-10-15-bar","102":"marca-sfc-110s-90-kw-8-11-15-bar","103":"marca-sfc-110st-90-kw-8-11-15-bar","104":"marca-sfc-110t-110-kw-10-15-bar","105":"marca-sfc-132-132-kw-8-11-15-bar","106":"marca-sfc-132s-132-kw-10-15-bar","107":"marca-sfc-132st-132-kw-10-15-bar","108":"marca-sfc-160-160-kw-8-12-15-bar","109":"marca-sfc-200-200-kw-8-12-15-bar","110":"marca-sfc-250-250-kw-8-12-15-bar","111":"marca-sfc-315-315-kw-8-12-15-bar","112":"marca-sfc-75-75-kw-9-bar","113":"marca-sfc-75t-75-kw-9-bar","114":"marca-sfc-90-90-kw-10-bar","115":"marca-sfc-90s-75-kw-8-11-15-bar","116":"marca-sfc-90st-75-kw-8-11-15-bar","117":"marca-sfc-90t-90-kw-10-bar","118":"marca-vs110-13a-2020","119":"marca-vs55-v4-zs1215759-75-12-2020","121":"first","122":"instock","123":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/keltec.com.br\/it\/wp-json\/wp\/v2\/product\/9456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/keltec.com.br\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/keltec.com.br\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/keltec.com.br\/it\/wp-json\/wp\/v2\/media\/43332"}],"wp:attachment":[{"href":"https:\/\/keltec.com.br\/it\/wp-json\/wp\/v2\/media?parent=9456"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/keltec.com.br\/it\/wp-json\/wp\/v2\/product_brand?post=9456"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/keltec.com.br\/it\/wp-json\/wp\/v2\/product_cat?post=9456"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/keltec.com.br\/it\/wp-json\/wp\/v2\/product_tag?post=9456"},{"taxonomy":"marca","embeddable":true,"href":"https:\/\/keltec.com.br\/it\/wp-json\/wp\/v2\/marca?post=9456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}