{"id":9559,"date":"2023-08-10T19:47:17","date_gmt":"2023-08-10T22:47:17","guid":{"rendered":"https:\/\/keltec.com.br\/produto\/kl660-009-2\/"},"modified":"2026-01-28T08:32:31","modified_gmt":"2026-01-28T11:32:31","slug":"kl660-009","status":"publish","type":"product","link":"https:\/\/keltec.com.br\/it\/prodotto\/kl660-009\/","title":{"rendered":"KL660-009"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":31609,"template":"","meta":[],"product_brand":[],"product_cat":[2698],"product_tag":[],"marca":[14283,14284,14285,14286,13406,14287,14293,16096,15250,15249,15392,15393,15394,15395,15391,15396,15397,13396,15514,15511,15520,15486,15516,15518,13399,13421,21200,13822,14973,13823,21202,13949,14992,14991,13950,15010,21204,13824,15014,15013,13946,15012,13951,15016,21206,15030,13825,15032,15033,13947,15031,13952,13826,15043,15044,15042,13953,13827,15055,15056,15057,15058,13948,13954,13420,14288,14289,13404,13423,14141,21092,14142,21094,21096,14143,21098,14144,21106,14145,21108,14835,19167,14916,15116,15689,15117,15690,14700,14701,14702,14860,14861,14862,14913,14863,14914,14915,19950,14864,14865,14866,15503,15644,13855,13856,14221,14594,14224,20997,14225,14226,13854,14612,21025,21027,21029,21031,14613,15119,15120,15121,15122,14703,16845,16840,16841,16842,16844,21131,19951,14290,14291,14292],"class_list":{"0":"post-9559","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-filtros-do-oleo-elementos","7":"marca-2110s-deutz-f3l1011f","8":"marca-2130s-deutz-f3l1011f","9":"marca-2150s-deutz-f3l1011f","10":"marca-2180s-deutz-f3l1011f","11":"marca-atlas-copco","12":"marca-c121-deutz-f3l1011f","13":"marca-c37-deutz-f3l1011f","14":"marca-c50-yanmar-4tnv88-2011-em-diante","15":"marca-c55-14","16":"marca-c55-14-yanmar-dlt0705-01-2017","17":"marca-c60-012","18":"marca-c60-012new","19":"marca-c65-10","20":"marca-c65-10-new","21":"marca-c76","22":"marca-c76-gardner-denver","23":"marca-c76-new","24":"marca-compair","25":"marca-ds1100-300-apos-2011-nta855c-cummins-211-bar-2011","26":"marca-ds900-350-apos-2011-nta855c-cummins-246-bar-2011","27":"marca-dt1100-300-apos-2011-nta855c-cummins-21-bar-2011","28":"marca-dt900-200-apos-2011-nta855c-cummins-14-bar-2011","29":"marca-dt900-300-apos-2011-nta855c-cummins-21-bar-2011","30":"marca-dt900-350-apos-2011-nta855c-cummins-246-bar-2011","31":"marca-elgi","32":"marca-fs-curtis","33":"marca-ga11-api310000-dez-25-13","34":"marca-ga11-brp072140-e-141-e-brp072285-jun-2012-15-hp","35":"marca-ga11-brp072140-out-2-009-15-hp-7-85-10-12-bar","36":"marca-ga11vsd-brp072140-e-141-e-brp072285-jun-2012-15-hp","37":"marca-ga15-api310000-dez-25-13","38":"marca-ga15-brp072140-e-141-e-brp072285-jun-2012-20-hp","39":"marca-ga15-brp072140-out-2-009-20-hp-7-85-10-12-bar","40":"marca-ga15vsd-brp072140-out-2-009-20-hp-7-85-10-12-bar","41":"marca-ga15vsd-brp072142-e-brp072285-jun-2012-20-hp","42":"marca-ga18-brp066292-2-007-25-hp-7-85-10-12-bar","43":"marca-ga18-api310000-dez-25-13","44":"marca-ga18-brp072140-e-141-e-brp072285-jun-2012-25-hp","45":"marca-ga18-brp072140-out-2-009-25-hp-7-85-10-12-bar","46":"marca-ga18ff-brp072140-out-2-009-25-hp-7-85-10-12-bar","47":"marca-ga18vsd-brp066292-ate-brp072284-exceto-brp072142-jan-2-008-25-hp","48":"marca-ga18vsd-brp072140-out-2-009-25-hp-7-85-10-12-bar","49":"marca-ga18vsd-brp072142-e-brp072285-fev-2013-25-hp","50":"marca-ga18vsd-brp082188-2-010-25-hp-7-85-10-12-bar","51":"marca-ga22-api310000-dez-25-13","52":"marca-ga22-brp066292-jan-2008-30-hp-7-85-10-12-bar","53":"marca-ga22-brp072140-e-141-e-brp072285-jun-2012-30-hp","54":"marca-ga22-brp072140-out-2-009-30-hp-7-85-10-12-bar","55":"marca-ga22ff-brp072140-out-2-009-30-hp-7-85-10-12-bar","56":"marca-ga22vsd-brp066292-ate-brp072284-exceto-brp072142-2-007-30-hp-7-85-10-12-bar","57":"marca-ga22vsd-brp072140-out-2-009-30-hp-7-85-10-12-bar","58":"marca-ga22vsd-brp072142-e-brp072285-30-hp","59":"marca-ga26-brp072140-e-141-e-brp072285-jun-2012-35-hp","60":"marca-ga26-brp072140-out-2-009-35-hp-7-85-10-12-bar","61":"marca-ga26ff-brp072140-out-2-009-35-hp-7-85-10-12-bar","62":"marca-ga26vsd-brp072140-out-2-009-35-hp-7-85-10-12-bar","63":"marca-ga26vsd-brp072142-e-brp072285-jun-2012-35-hp","64":"marca-ga30-brp072140-e-141-e-brp072285-jun-2012-40-hp","65":"marca-ga30-brp072140-out-2-009-40-hp-7-85-10-12-bar","66":"marca-ga30-vsd-brp072140-out-2-009-40-hp-7-85-10-12-bar","67":"marca-ga30-brp072140-out-2-009-40-hp-7-85-10-12-bar-atlas-copco","68":"marca-ga30ff-brp072140-out-2-009-40-hp-7-85-10-12-bar","69":"marca-ga30vsd-brp066292-ate-brp072284-exceto-brp072142-40-hp","70":"marca-ga30vsd-brp072142-e-brp072285-fev-2-013-40-hp","71":"marca-gardner-denver","72":"marca-h37-deutz-f3l1011f","73":"marca-h51-deutz-f3l1011f","74":"marca-ingersoll-rand","75":"marca-kaeser","76":"marca-l23-30-hp-zs1090409-nov-2013","77":"marca-l23-v2-30hp-zs1090409-nov-2013","78":"marca-l23rs-30-hp-zs1090409-nov-2013","79":"marca-l23rs-v2-30hp-zs1090409-nov-2013","80":"marca-l26-v2-35hp-zs1090409-nov-2013","81":"marca-l26rs-35-hp","82":"marca-l26rs-v2-35hp-zs1090409-nov-2013","83":"marca-l29-40-hp-zs1090409-nov-2013","84":"marca-l29-v2-40hp-zs1090409-nov-2013","85":"marca-l29rs-40-hp-zs1090409-nov-2013","86":"marca-l29rs-v2-40hp-zs1090409-nov-2013","87":"marca-l45sr-60-hp","88":"marca-m120t","89":"marca-nirvana-irn100h-cc-nv6100-135-hp-44-10-bar","90":"marca-nirvana-irn15-80445372-20-hp-jan-2009","91":"marca-nirvana-irn15-high-dust-option-80445372-20-hp-jan-2009","92":"marca-nirvana-irn185-80445372-25-hp-jan-2009","93":"marca-nirvana-irn185-high-dust-option-80445372-25-hp-jan-2009","94":"marca-nirvana-irn22-80445372-30-hp-jan-2009","95":"marca-nirvana-irn25-80445372-25-hp-jan-2009","96":"marca-nirvana-irn30-80445372-40-hp-jan-2009","97":"marca-nirvana-irn37k-cc-2710500-50-hp-44-10-bar","98":"marca-nirvana-irn45k-cc-2730450-50-hp-44-10-bar","99":"marca-nirvana-irn50h-cc-nnv2100-65-hp-44-10-bar","100":"marca-nirvana-irn55k-cc-2750330-75-hp-44-10-bar","101":"marca-nirvana-irn60h-cc-nnv2100-80-hp-44-10-bar","102":"marca-nirvana-irn75h-cc-nv6100-100-hp-44-10-bar","103":"marca-nirvana-irn75k-cc-2770650-100-hp-44-10-bar","104":"marca-qingdao-huitongxinda-air","105":"marca-r30i-b1016i0030-40-hp-set-14","106":"marca-r30n-b1016i0030-40-hp-set-14","107":"marca-r37-b1016i0030-50-hp-set-14","108":"marca-sa250-350-hp","109":"marca-sprint-050-057","110":"marca-ssr-37-bomba-de-vacuo-2272000","111":"marca-ssr-45-bomba-de-vacuo-2280250","112":"marca-ssr-ep40se-b-40-hp","113":"marca-ssr-ep60se-60-hp","114":"marca-ssr-hp40se-b-40-hp-96-bar","115":"marca-ssr-hp60se-60hp-jun-05","116":"marca-ssr-hxp40se-b-40-hp-138-bar","117":"marca-ssr-hxp50se-50-hp-138-bar","118":"marca-ssr-m37b-bomba-de-vacuo-2260600","119":"marca-ssr-m55-from-78550","120":"marca-ssr-mh37se-50hp-138bar-jun-05","121":"marca-ssr-ml37se-50hp-138bar-jun-05","122":"marca-ssr-mm37se-50hp-138bar-jun-05","123":"marca-ssr-mu37se-50hp-138bar-80440464-jun-05","124":"marca-ssr-xf50se-50-hp-69-bar","125":"marca-up6-15-22083745-15-hp-125-150-210-bar-jan-05","126":"marca-up6-20-22083745-20-hp-125-150-210-bar-jan-05","127":"marca-up6-25-22083745-25-hp-125-150-210-bar-jan-05","128":"marca-up6-30-22083745-30-hp-125-150-210-bar-jan-05","129":"marca-up6-50-50-hp","130":"marca-utiliza-1-peca-dt1100-300-apos-2011-nta855c-cummins-21-bar-2011","131":"marca-utiliza-1-peca-ds900-350-apos-2011-nta855c-cummins-246-bar-2011","132":"marca-utiliza-1-peca-ds1100-300-apos-2011-nta855c-cummins-211-bar-2011","133":"marca-utiliza-1-peca-dt900-200-apos-2011-nta855c-cummins-14-bar-2011","134":"marca-utiliza-1-peca-dt900-350-apos-2011-nta855c-cummins-246-bar-2011","135":"marca-vs29-v2-40hp-12-2024","136":"marca-xv22-16g","137":"marca-z150s-deutz-f3l1011f","138":"marca-z2150s-deutz-f3l1011f","139":"marca-z2180hs-deutz-f3l1011f","141":"first","142":"instock","143":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/keltec.com.br\/it\/wp-json\/wp\/v2\/product\/9559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/keltec.com.br\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/keltec.com.br\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/keltec.com.br\/it\/wp-json\/wp\/v2\/media\/31609"}],"wp:attachment":[{"href":"https:\/\/keltec.com.br\/it\/wp-json\/wp\/v2\/media?parent=9559"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/keltec.com.br\/it\/wp-json\/wp\/v2\/product_brand?post=9559"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/keltec.com.br\/it\/wp-json\/wp\/v2\/product_cat?post=9559"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/keltec.com.br\/it\/wp-json\/wp\/v2\/product_tag?post=9559"},{"taxonomy":"marca","embeddable":true,"href":"https:\/\/keltec.com.br\/it\/wp-json\/wp\/v2\/marca?post=9559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}