{"id":9783,"date":"2023-08-10T19:48:05","date_gmt":"2023-08-10T22:48:05","guid":{"rendered":"https:\/\/keltec.com.br\/produto\/kx300-026-2\/"},"modified":"2025-12-01T10:31:26","modified_gmt":"2025-12-01T13:31:26","slug":"kx300-026-2","status":"publish","type":"product","link":"https:\/\/keltec.com.br\/it\/prodotto\/kx300-026-2\/","title":{"rendered":"KX300-026"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Transdutor de press\u00e3o<\/p>","protected":false},"featured_media":0,"template":"","meta":[],"product_brand":[],"product_cat":[2701],"product_tag":[],"marca":[13404,14221,14589,14594,14224,14220,20997,14225,14226,21025,21027,21029,21031,14613],"class_list":["post-9783","product","type-product","status-publish","product_cat-reparo-de-valvulas","marca-ingersoll-rand","marca-ssr-ep40se-b-40-hp","marca-ssr-ep50se-50-hp-86-bar","marca-ssr-ep60se-60-hp","marca-ssr-hp40se-b-40-hp-96-bar","marca-ssr-hp50se-50-hp-96-bar","marca-ssr-hp60se-60hp-jun-05","marca-ssr-hxp40se-b-40-hp-138-bar","marca-ssr-hxp50se-50-hp-138-bar","marca-ssr-mh37se-50hp-138bar-jun-05","marca-ssr-ml37se-50hp-138bar-jun-05","marca-ssr-mm37se-50hp-138bar-jun-05","marca-ssr-mu37se-50hp-138bar-80440464-jun-05","marca-ssr-xf50se-50-hp-69-bar","first","instock","product-type-simple"],"_links":{"self":[{"href":"https:\/\/keltec.com.br\/it\/wp-json\/wp\/v2\/product\/9783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/keltec.com.br\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/keltec.com.br\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/keltec.com.br\/it\/wp-json\/wp\/v2\/media?parent=9783"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/keltec.com.br\/it\/wp-json\/wp\/v2\/product_brand?post=9783"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/keltec.com.br\/it\/wp-json\/wp\/v2\/product_cat?post=9783"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/keltec.com.br\/it\/wp-json\/wp\/v2\/product_tag?post=9783"},{"taxonomy":"marca","embeddable":true,"href":"https:\/\/keltec.com.br\/it\/wp-json\/wp\/v2\/marca?post=9783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}