{"id":39767,"date":"2025-12-18T15:32:47","date_gmt":"2025-12-18T18:32:47","guid":{"rendered":"https:\/\/keltec.com.br\/?post_type=product&#038;p=39767"},"modified":"2026-04-09T16:17:32","modified_gmt":"2026-04-09T19:17:32","slug":"kl990-007s","status":"publish","type":"product","link":"https:\/\/keltec.com.br\/pt\/produto\/kl990-007s\/","title":{"rendered":"KL990-007S"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":39768,"template":"","meta":[],"product_brand":[],"product_cat":[2698],"product_tag":[],"marca":[20966,20967,20775,20776,20777,20964,20965,20778,20779,14583,14582,14585,14584,14587,14586,20963,15514,14007,14037,14038,15523,15511,15520,14039,14040,15486,15516,15518,13399,19189,19191,19190,13421,15464,13494,13493,14332,15469,13492,13495,13496,15723,15696,15697,15698,13404,14501,21371,21385,14502,14503,14504,21373,21387,14505,14506,14507,21375,21389,14508,14509,14510,14511,14498,21369,21383,14499,14500,15465,16107,19201,15487,15488,15489,14264,14265,14266,14267,15650,14263,14512,14597,14598,14599,15294,15295,15296,15297,15298,15299,15302,15300,20985,15301,15305,15303,20987,15304,14250,20989,20991,14251,20993,14252,14590,14591,14595,14596,15306,14253,20995,14607,20998,14580,15307,15308,15309,15310,15311,15312,15333,15313,15334,15314,15315,14254,14255,14256,14257,14258,14259,14603,14605,14606,21000,15316,21002,21004,14260,21006,21009,21011,21013,21015,21017,21021,21023,14610,14611,21035,21042,21039,21044,14581,14617,15317,15318,15319,15320,15321,15322,15335,15323,15336,15324,14261,14616,14615,15325,15326,21046,21048,14262,21050,21052,21054,14621,14622,15327,15328,15329,15330,15331,15332,14619,14620,13400,21049,16600,20986,16593,16601,21024,21055,20992,16596,21018,21051,16602,21014,21047,16597,20994,16598,21022,21053,21016,21386,21388,21390,21384,20988,20990,20996,21001,21003,21005,21007,21010,21012,21372,21374,21376,21370,15699,14321,15458,15459,15499,14322,14323,15700,15701],"class_list":["post-39767","product","type-product","status-publish","has-post-thumbnail","product_cat-filtros-do-oleo-elementos","marca-10-125-cummins-f3-8-hp-9bar-01-2021","marca-14-115-cummins-f3-8-hp-9bar-01-2021","marca-550rh-cummins","marca-600rh-cummins","marca-600xh-cummind","marca-7-124-cummins-9bar-01-2016","marca-7-125-cummins-f3-8-hp-9bar-01-2021","marca-750h-cummins","marca-750rh-cummins","marca-cougar-ep100-100-hp-86-bar","marca-cougar-ep75-75-hp-86-bar","marca-cougar-hp100-100-hp-96-bar","marca-cougar-hp75-75-hp-96-bar","marca-cougar-xf100-100-hp-69-bar","marca-cougar-xf75-75-hp-69-bar","marca-doosan-daewoo","marca-ds1100-300-apos-2011-nta855c-cummins-211-bar-2011","marca-ds1200-350-nta855c-cummins-246-bar","marca-ds600-200-apos-2011-6cta8-3-cummins-14-bar-2011","marca-ds650-200-apos-2011-6cta8-3-cummins-14-bar-2011","marca-ds900-100","marca-ds900-350-apos-2011-nta855c-cummins-246-bar-2011","marca-dt1100-300-apos-2011-nta855c-cummins-21-bar-2011","marca-dt600-100-antes-2011-6bta-cummins-7-bar-2011","marca-dt650-200-antes-2011-6bta-cummins-14-bar-2011","marca-dt900-200-apos-2011-nta855c-cummins-14-bar-2011","marca-dt900-300-apos-2011-nta855c-cummins-21-bar-2011","marca-dt900-350-apos-2011-nta855c-cummins-246-bar-2011","marca-elgi","marca-fac212p","marca-face250p","marca-facg212p","marca-fs-curtis","marca-hp300wcu-cum4bta39116","marca-hp375-cummins","marca-hp375-isuzu","marca-hp375-john-deere","marca-hp375-antigo-cummins","marca-hp425-cummins","marca-hp425awir-isuzu","marca-hp425awir-john-deere","marca-hp525","marca-hp600wcu-cum6cta83","marca-hp750wcu-cum6cta83","marca-hp935","marca-ingersoll-rand","marca-nirvana-irn100h-2s-nff0118-135-hp-44-10-bar","marca-nirvana-irn110k-cc-n22186472-jul2005","marca-nirvana-irn110k-high-dust-cc-n22186472-jul2005","marca-nirvana-irn110k-2s-2850000-145-hp-44-10-bar","marca-nirvana-irn110k-cc-2800008-145-hp-44-10-bar","marca-nirvana-irn125h-cc-nff50148-170-hp-44-10-bar","marca-nirvana-irn132k-cc-n22186472-jul2005","marca-nirvana-irn132k-high-dust-cc-n22186472-jul2005","marca-nirvana-irn132k-2s-2860000-175-hp-44-10-bar","marca-nirvana-irn132k-cc-2810002-175-hp-44-10-bar","marca-nirvana-irn150h-cc-200-hp-44-10-bar","marca-nirvana-irn160k-cc-n22186472-jul2005","marca-nirvana-irn160k-high-dust-cc-n22186472-jul2005","marca-nirvana-irn160k-2s-2870000-215-hp-44-10-bar","marca-nirvana-irn160k-cc-2820006-215-hp-44-10-bar","marca-nirvana-irn200h-2s-nff0118-270-hp-44-10-bar","marca-nirvana-irn200h-cc-nf50148-270-hp-44-10-bar","marca-nirvana-irn75k-2s-2830000-100-hp-44-10-bar","marca-irn90k-cc-n22186472-jul-2005","marca-nirvana-irn90k-high-dust-cc-n22186472-jul-2005","marca-nirvana-irn90k-2s-n2840000-120-hp-44-10-bar","marca-nirvana-irn90k-cc-n2790010-120-hp-44-10-bar","marca-p375wcu-cum4bta39116","marca-p425wir-4ird5ae","marca-pg1200-350","marca-pg650-200-2016","marca-pg900-100-2016","marca-pg900-200-2016","marca-r110iu-80443070-150-hp-jul-07","marca-r132iu-80443070-175-hp-jul-07","marca-r150iu-200-hp-jul-07","marca-r160iu-80443070-225-hp-jul-07","marca-r160iu-hd-80443070-225-hp-jul-07","marca-r90iu-80443070-125-hp-jul-07","marca-r90iu-standard-canister-80443070-125-hp-jul-07","marca-ssr-ep100-100-hp-86-bar","marca-ssr-ep100-80440456-100-hp-86-bar-jul-07","marca-ssr-ep100br-80440456-100-hp-86-bar-jul-07","marca-ssr-ep125-125-hp-86-bar","marca-ssr-ep125br-125-hp-86-bar","marca-ssr-ep150-125-hp-86-bar","marca-ssr-ep150br-150-hp-86-bar","marca-ssr-ep200-200-hp-86-bar","marca-ssr-ep200br-200-hp-86-bar","marca-ssr-ep250-250-hp","marca-ssr-ep250-250-hp-86-bar","marca-ssr-ep250-2s-250hp-jun-07","marca-ssr-ep250br-250-hp-86-bar","marca-ssr-ep300-300-hp","marca-ssr-ep300-300-hp-86-bar","marca-ssr-ep300-2s-300hp-jun-07","marca-ssr-ep300br-300-hp-86-bar","marca-ssr-ep350-350-hp-86-bar","marca-ssr-ep350-2s-350hp-86bar-jun-07","marca-ssr-ep400-2s-400hp-86bar-jun-07","marca-ssr-ep450-450-hp-86-bar","marca-ssr-ep450-2s-450hp-86bar-jun-07","marca-ssr-ep450i-450-hp-86-bar","marca-ssr-ep60-60-hp-86-bar","marca-ssr-ep60se-60-hp-86-bar","marca-ssr-ep75-75-hp-86-bar","marca-ssr-ep75br-80440456-75-hp-86-bar-jul-07","marca-ssr-epe300-300-hp-86-bar","marca-ssr-epe400-400-hp-86-bar","marca-ssr-epe500-2s-500hp-86bar-jun-07","marca-ssr-hp100-100-hp-96-bar","marca-ssr-hp100-80440456-100hp-96bar-jul-07","marca-ssr-hp100br-80440456-100-hp-96-bar-jul-07","marca-ssr-hp125-125-hp-96-bar","marca-ssr-hp125br-125-hp-96-bar","marca-ssr-hp150-150-hp-96-bar","marca-ssr-hp150br-150-hp-96-bar","marca-ssr-hp200-200-hp-96-bar","marca-ssr-hp200br-200-hp-96-bar","marca-ssr-hp250-250-hp-96-bar","marca-ssr-hp250br-250-hp-96-bar","marca-ssr-hp300-300-hp-96-bar","marca-ssr-hp300br-300-hp-96-bar","marca-ssr-hp300i-300-hp-96-bar","marca-ssr-hp350-350-hp-96-bar","marca-ssr-hp350i-350-hp-96-bar","marca-ssr-hp400-400-hp-96-bar","marca-ssr-hp400i-400-hp-96-bar","marca-ssr-hp450-450-hp-96-bar","marca-ssr-hp450i-450-hp-96-bar","marca-ssr-hp60se-60-hp-96-bar","marca-ssr-hp75-80440456-75-hp-96-bar-jul-07","marca-ssr-hp75br-80440456-75-hp-96-bar-jul-07","marca-ssr-hpe250-2s-250hp-96-jun-07","marca-ssr-hpe300-300-hp-96-bar","marca-ssr-hpe300-2s-300hp-96bar-jun-07","marca-ssr-hpe350-2s-350hp-96bar-jun-07","marca-ssr-hpe400-400-hp-96-bar","marca-ssr-hpe400-2s-400hp-96bar-jun-07","marca-ssr-hpe450-2s-450hp-96bar-jun-07","marca-ssr-hpe500-2s-500hp-96bar-jun-07","marca-ssr-hxpe250-2s-250hp-96bar-jun-07","marca-ssr-hxpe300-2s-300hp-96bar-jun-07","marca-ssr-hxpe350-2s-350hp-96bar-jun-07","marca-ssr-hxpe450-2s-450hp-96bar-jun-07","marca-ssr-hxpe500-2s-500hp-96bar-jun-07","marca-ssr-mhmlmm55-80440456-75-hp-jul-07","marca-ssr-mhmlmm75-80440456-100-hp-jul-07","marca-ssr-mh55-80440456-75hp-jul-07","marca-ssr-ml75-80440456-100hp-jul-07","marca-ssr-mm55-80440456-75hp-jul-07","marca-ssr-mm75-80440456-100hp-jul-07","marca-ssr-xf100br-80440456-100-hp-69-bar-jul-07","marca-ssr-xf100usa-100-hp-69-bar","marca-ssr-xf125-125-hp-69-bar","marca-ssr-xf125br-125-hp-69-bar","marca-ssr-xf150-150-hp-69-bar","marca-ssr-xf150br-150-hp-69-bar","marca-ssr-xf200-200-hp-69-bar","marca-ssr-xf200br-200-hp-69-bar","marca-ssr-xf250-250-hp-69-bar","marca-ssr-xf250br-250-hp-69-bar","marca-ssr-xf300-300-hp-69-bar","marca-ssr-xf300br-300-hp-69-bar","marca-ssr-xf450-450-hp-69-bar","marca-ssr-xf75-usa-100-hp-69-bar","marca-ssr-xf75br-80440456-75-hp-69-bar","marca-ssr-xfe250-2s-250-hp-69-bar-jun-07","marca-ssr-xfe300-300-hp-69-bar","marca-ssr-xfe300-2s-300hp-69bar-jun-07","marca-ssr-xfe350-2s-350hp-69bar-jun-07","marca-ssr-xfe400-400-hp-69-bar","marca-ssr-xfe400-s2-400hp-69bar-jun-07","marca-ssr-xfe450-2s-450hp-69bar-jun-07","marca-ssr-xfe500-s2-500hp-69bar-jun-07","marca-ssr-xp100-80440456-100-hp-113-bar-jul-07","marca-ssr-xp100br-80440456-100-hp-113-bar-jul-07","marca-ssr-xp150-150-hp-113-bar","marca-ssr-xp150br-150-hp-113-bar","marca-ssr-xp200-200-hp-113-bar","marca-ssr-xp200br-200-hp-113-bar","marca-ssr-xp250-200-hp-113-bar","marca-ssr-xp250br-200-hp-113-bar","marca-ssr-xp75-80440456-75-hp-113-bar-jul-07","marca-ssr-xp75br-80440456-75-hp-113-bar-jul-07","marca-sullair","marca-utiliza-2-pecas-ssr-xfe350-2s-350hp-69bar-jun-07","marca-utiliza-2-pecas-ssr-ep250-250-hp-86-bar","marca-utiliza-2-pecas-ssr-ep250-2s-250hp-jun-07","marca-utiliza-2-pecas-ssr-xfe250-2s-250-hp-69-bar","marca-utiliza-2-pecas-ssr-ep250-250-hp","marca-utiliza-2-pecas-ssr-hxpe500-2s-500hp-96bar-jun-07","marca-utiliza-2-pecas-ssr-xfe500-s2-500hp-69bar-jun-07","marca-utiliza-2-pecas-ssr-ep400-2s-400hp-86bar-jun-07","marca-utiliza-2-pecas-r132iu-80443070-175-hp-jul-07","marca-utiliza-2-pecas-ssr-hxpe350-2s-350hp-96bar-jun-07","marca-utiliza-2-pecas-ssr-xfe400-s2-400hp-69bar-jun-07","marca-utiliza-2-pecas-ssr-ep300-300-hp","marca-utiliza-2-pecas-ssr-hxpe250-2s-250hp-96bar-jun-07","marca-utiliza-2-pecas-ssr-xfe300-2s-300hp-69bar-jun-07","marca-utiliza-2-pecas-r150iu-200-hp-jul-07","marca-utiliza-2-pecas-ssr-ep450-2s-450hp-86bar-jun-07","marca-utiliza-2-pecas-r160iu-80443070-225-hp-jul-07","marca-utiliza-2-pecas-ssr-hxpe450-2s-450hp-96bar-jun-07","marca-utiliza-2-pecas-ssr-xfe450-2s-450hp-69bar-jun-07","marca-utiliza-2-pecas-ssr-hxpe300-2s-300hp-96bar-jun-07","marca-utiliza-2-pecas-110-high","marca-utiliza-2-pecas-132-high","marca-utiliza-2-pecas-160-high","marca-utiliza-2-pecas-90-high","marca-utiliza-2-pecas-ep300","marca-utiliza-2-pecas-ep350-2s","marca-utiliza-2-pecas-epe500","marca-utiliza-2-pecas-hpe250","marca-utiliza-2-pecas-hpe300","marca-utiliza-2-pecas-hpe350","marca-utiliza-2-pecas-hpe400","marca-utiliza-2-pecas-hpe450","marca-utiliza-2-pecas-hpe500","marca-utiliza-2-pecas-irn110k","marca-utiliza-2-pecas-irn132k","marca-utiliza-2-pecas-irn160k","marca-utiliza-2-pecas-nirvana","marca-vhp825wcu-cummins","marca-xhp1070wcat-cat3406","marca-xhp660-860107-ate-860499","marca-xhp760-860107-ate-860499","marca-xhp850-350","marca-xhp900wcat-cat3406-24-bar","marca-xp600","marca-xp750wcu-cum6cta83","marca-xp825wcu-cum6cta83","first","instock","product-type-simple"],"_links":{"self":[{"href":"https:\/\/keltec.com.br\/pt\/wp-json\/wp\/v2\/product\/39767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/keltec.com.br\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/keltec.com.br\/pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/keltec.com.br\/pt\/wp-json\/wp\/v2\/media\/39768"}],"wp:attachment":[{"href":"https:\/\/keltec.com.br\/pt\/wp-json\/wp\/v2\/media?parent=39767"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/keltec.com.br\/pt\/wp-json\/wp\/v2\/product_brand?post=39767"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/keltec.com.br\/pt\/wp-json\/wp\/v2\/product_cat?post=39767"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/keltec.com.br\/pt\/wp-json\/wp\/v2\/product_tag?post=39767"},{"taxonomy":"marca","embeddable":true,"href":"https:\/\/keltec.com.br\/pt\/wp-json\/wp\/v2\/marca?post=39767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}